{"id":10750,"date":"2023-05-17T21:04:26","date_gmt":"2023-05-18T05:04:26","guid":{"rendered":"https:\/\/www.entremundos.org\/revista\/?p=10750"},"modified":"2023-05-17T21:05:28","modified_gmt":"2023-05-18T05:05:28","slug":"10750","status":"publish","type":"post","link":"https:\/\/www.entremundos.org\/revista\/medio-ambiente\/10750\/","title":{"rendered":"Voces por el cuidado, libertad y defensa del agua"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Maiz de vida\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cLos pueblos, las comunidades, los barrios y colonias con conciencia, queremos decir con firmeza que anhelamos PERMANECER EN EL TERRITORIO PARA VIVIR CON DIGNIDAD. Para eso, invitamos a todos los pueblos y naciones a organizarnos en resistencia y asegurar las din\u00e1micas de autogobierno y las estrategias que permitan un uso plural y equitativo del agua para las personas y para todos los seres vivos cuya vida depende de ella.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Queremos, desde esta asamblea de pueblos y autoridades plurinacionales, reconocer la resistencia y la capacidad de defensa de miles de mujeres, hombres, ni\u00f1os y ni\u00f1as que, ante las amenazas y presiones de empresas y gobiernos, defienden la vida, defienden el agua, defienden sus derechos a ser y estar en el mundo.\u201d Fragmento del comunicado de la II Segunda Cumbre por el Agua.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> <a href=\"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2977.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10702 aligncenter\" src=\"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2977.jpg?resize=300%2C169&#038;ssl=1\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2977.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2977.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2977.jpg?resize=335%2C188&amp;ssl=1 335w, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2977.jpg?w=1000&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">El agua es un ser vivo en la cosmovisi\u00f3n de los pueblos de Abya Yala.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el marco del d\u00eda mundial del agua, m\u00e1s de 300 personas de los pueblos maya, xinka, gar\u00edfuna y mestizo se reunieron en un encuentro plurinacional por la libertad y defensa del agua en San Pedro la Laguna, Solol\u00e1.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el encuentro se articularon defensoras y defensores quienes realizaron m\u00faltiples conversatorios, mesas de di\u00e1logo y presentaciones de arte.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La comunidad Tz\u2019unun Ya\u2019 y un grupo de mujeres que limpian el lago fueron las anfitrionas de esta cumbre. Berta Navichoc, gu\u00eda espiritual e integrante de la comunidad, realiz\u00f3 en conjunto con sus compa\u00f1eras una acci\u00f3n art\u00edstica para concientizar sobre el da\u00f1o que los desechos industriales y la basura le causan a Qatee\u2019 Ya\u2019 como le llaman en el territorio Tzutujil al lago de Atitl\u00e1n. La agrupaci\u00f3n de mujeres hizo un performance \u201cTu industria, tu basura\u201d, una acci\u00f3n realizada meses atr\u00e1s en donde caminaron hacia la C\u00e1mara de la Industria y el Congreso de la Rep\u00fablica de Guatemala para devolver la basura generada por la industria y el sistema de consumo impuesto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">\u201cCaricias del agua\u201d su intervenci\u00f3n fue alrededor de los oc\u00e9anos, lagos y r\u00edos que forman parte de los distintos territorios.\u00a0 Abelino Mej\u00eda mencion\u00f3 que la problem\u00e1tica que afecta a las comunidades de la costa sur es el desv\u00edo y el uso desmedido de agua por la industria ca\u00f1era, y est\u00e1 da\u00f1ando el ecosistema del \u00e1rea protegida manglar del Manch\u00f3n Guamuchal en el Pac\u00edfico guatemalteco, provocando el cierre de la bocabarra que drena hacia el mar en el \u00e1rea del Chico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el conversatorio \u201cVoces por la defensa del agua\u201d profesionales en leyes y en derechos humanos abordaron el tema de la criminalizaci\u00f3n y cooptaci\u00f3n del Estado y el despojo del agua a las comunidades. Bernardo Caal Xol, uno de los defensores de los recursos naturales, mencion\u00f3 que no existen leyes que defiendan a los pueblos originarios. La \u00fanica ley es el derecho a la Consulta Comunitaria, pero por ejercer y defender el r\u00edo Cahab\u00f3n fue llevado a prisi\u00f3n. La abogada Carmela Curup, del Bufete para Pueblos Ind\u00edgenas, evidencio que existen 1 mil 200 \u00f3rdenes de captura para defensoras y defensores en Alta Verapaz.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el espacio \u201cResistiendo junto al agua\u201d se reflexion\u00f3 sobre los impactos del extractivismo en los territorios; la miner\u00eda a cielo abierto, las licencias y malas pr\u00e1cticas de empresas. Tambi\u00e9n se estuvieron realizando pruebas de la calidad de agua con los cient\u00edficos comunitarios xinkas y el Observatorio de industrias extractivas (OIE), para analizar los efectos de la miner\u00eda en el agua de las comunidades.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Observatorio de Industrias extractivas expuso que existen actualmente 683 solicitudes para licencias de exploraci\u00f3n y explotaci\u00f3n minera.<\/span><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2788.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10700 aligncenter\" src=\"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2788.jpg?resize=300%2C169&#038;ssl=1\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2788.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2788.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2788.jpg?resize=335%2C188&amp;ssl=1 335w, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/cue2788.jpg?w=1000&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><b>Sin tierras para cultivar\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El Movimiento de Comunidades en defensa del agua Qana&#8217; Ch&#8217;och&#8217; estuvo presente en esta cumbre, siendo los mayores afectados por la p\u00e9rdida de la biodiversidad y las tierras cultivables en la regi\u00f3n de Ixc\u00e1n y Raxruh\u00e1, Alta Verapaz.\u00a0 El monocultivo de palma de aceite es una problem\u00e1tica presente en el \u00e1rea norte del pa\u00eds.\u00a0 Seg\u00fan David Paredes, de la Red Nacional por la Defensa de la Soberan\u00eda Alimentaria en Guatemala (REDSAG),\u00a0 es urgente una iniciativa de ley que proteja la biodiversidad, las semillas nativas y la soberan\u00eda alimentaria de los pueblos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vecinos afectados de \u00e1reas urbanas se quejan que la empresa municipal de agua de la capital vende el vital l\u00edquido a zonas residenciales y a sectores privilegiados.\u00a0 Judith Valle expres\u00f3 que el agua es un derecho humano y no un privilegio. El Colectivo Chiviricuarta se est\u00e1 organizando para hacer frente a la problem\u00e1tica en Palencia.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Uno de los principales foros fue \u201cPermanecer en el territorio para vivir con dignidad\u201d un espacio dedicado a las mujeres y el cuidado del agua, en donde Mar\u00eda Jacinta X\u00f3n, antrop\u00f3loga Maya k\u02bciche\u02bc y activista por los derechos de los pueblos originarios de Guatemala, tuvo el tiempo para dialogar con Sadia Lujan y Luz Mary Quispe, las compa\u00f1eras de la red de mujeres lideresas unidas por el lago Titikaka, de sur Am\u00e9rica, quienes visitaron Guatemala para compartir sus experiencias desde el lago Peruano con las red de mujeres del lago de Atitl\u00e1n.<\/span><\/p>\n<p><b>No m\u00e1s criminalizaci\u00f3n\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El evento fue dedicado a las mujeres que cuidan y defienden el lago de Atitl\u00e1n, al Movimiento de comunidades en defensa del agua Qana\u2019 Ch\u2019och\u2019, a la Gremial de Pescadores del Estor, a la Resistencia de Cahab\u00f3n, Resistencia de Carch\u00e1, Resistencia de San Juan Sacatep\u00e9quez, Resistencia Maya Ch\u2019orti de Olopa y Quetzaltepeque, Consejo de comunidades de la Costa Sur, Parlamento Xinka, y a las Mujeres de Semuy II.\u00a0 Todas estas acciones de defensa han sido perseguidas y criminalizadas por el Estado de Guatemala. As\u00ed mismo se hizo menci\u00f3n de las compa\u00f1eras Virginia Laparra, ex fiscal del Ministerio P\u00fablico, quien ha estado en prisi\u00f3n por m\u00e1s de un a\u00f1o por denunciar actos de corrupci\u00f3n y ahora es perseguida.<\/span><\/p>\n<p><b>Arte y defensa<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Todo el evento estuvo acompa\u00f1ado de actividades y expresiones art\u00edsticas, entre ellas la m\u00fasica de <\/span><i><span style=\"font-weight: 400;\">Selva y Cerro <\/span><\/i><span style=\"font-weight: 400;\">que acompa\u00f1\u00f3 una ceremonia espiritual a orillas de la playa; el grupo de danza y m\u00fasica Sot\u2019zil realiz\u00f3 una presentaci\u00f3n inspirada en los elementos naturales y la cosmovisi\u00f3n presente en el Popol Vuj; las compa\u00f1eras de Colectiva Teatro, presentaron por primera vez \u201cTzultaqaa\u2019\u201d una obra de teatro de sombras que habla sobre criminalizaci\u00f3n. Manuel Chavajay fue uno de los artistas con mayor presencia en la cumbre, varias de sus obras inspiradas en el tema del agua embellecieron cada uno de los espacios y acciones que se realizaron. Tambi\u00e9n hubo marimba en la noche cultural y m\u00faltiples ventas de productos agroecol\u00f3gicos y las iniciativas artesanales estuvieron presentes en el encuentro.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La cumbre finaliz\u00f3 con una caminata y ofrenda de flores alrededor del lago de Atitl\u00e1n, en donde en una acci\u00f3n pol\u00edtica se ley\u00f3 el pronunciamiento y se reiter\u00f3 el compromiso de seguir defendiendo el agua. Abelino Chub Caal, enfatiz\u00f3 la importancia de realizar estos encuentros plurinacionales para seguir fortaleciendo las luchas desde las comunidades.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Valeria Leiva, ecologista, fot\u00f3grafa y comunicadora de ma\u00edz de vida.<\/span><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/img_2326.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10710 aligncenter\" src=\"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/img_2326.jpg?resize=225%2C300&#038;ssl=1\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/img_2326.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/img_2326.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/img_2326.jpg?resize=335%2C447&amp;ssl=1 335w, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/img_2326.jpg?w=1000&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maiz de vida\u00a0 \u201cLos pueblos, las comunidades, los barrios y colonias con conciencia, queremos decir con firmeza que anhelamos PERMANECER EN EL TERRITORIO PARA VIVIR CON DIGNIDAD. Para eso, invitamos a todos los pueblos y naciones a organizarnos en resistencia y asegurar las din\u00e1micas de autogobierno y las estrategias que permitan un uso plural y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[396,394,452,397,384,399,406,398],"tags":[535,14,4289,4291,489,4159,4288,1233,3176,376,4292,4290,528],"class_list":["post-10750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bosques","category-cambio-climatico","category-frontpage","category-mar","category-medio-ambiente","category-megaproyectos","category-megaproyectos-2","category-rios","tag-activistas","tag-agua","tag-arte-y-defensa","tag-campanas-de-defensa","tag-criminalizacion","tag-defensa-del-territorio-en-guatemala","tag-defensa-por-el-agua","tag-defensores","tag-desarrollo-y-medio-ambiente","tag-medio-ambiente","tag-mega-proyectos","tag-persecucion","tag-territorio"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/05\/img_2350.jpg?fit=1500%2C1125&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/s7ljt7-10750","jetpack-related-posts":[{"id":12859,"url":"https:\/\/www.entremundos.org\/revista\/politica\/mujeres-indigenas-y-rurales-en-defensa-del-territorio-frente-al-extractivismo-en-guatemala\/","url_meta":{"origin":10750,"position":0},"title":"Mujeres ind\u00edgenas y rurales en defensa del territorio frente al extractivismo en Guatemala","author":"EntreMundos","date":"21 mayo, 2025","format":false,"excerpt":"Por Asociadas Por lo Justo (JASS) Este es un resumen de un mapeo realizado por JASS, para compartir sus an\u00e1lisis, sus luchas y los impactos en sus vidas. El objetivo es contar las luchas por el territorio frente al extractivismo en Guatemala e identificar el papel y el impacto en\u2026","rel":"","context":"En \u00abFrontPage\u00bb","block_context":{"text":"FrontPage","link":"https:\/\/www.entremundos.org\/revista\/category\/frontpage\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2025\/05\/2-scaled.png?fit=1200%2C843&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2025\/05\/2-scaled.png?fit=1200%2C843&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2025\/05\/2-scaled.png?fit=1200%2C843&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2025\/05\/2-scaled.png?fit=1200%2C843&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2025\/05\/2-scaled.png?fit=1200%2C843&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10580,"url":"https:\/\/www.entremundos.org\/revista\/politica\/desalojos-aumentan-durante-el-gobierno-de-alejandro-giammattei\/","url_meta":{"origin":10750,"position":1},"title":"Desalojos aumentan durante el gobierno de Alejandro Giammattei","author":"EntreMundos","date":"8 marzo, 2023","format":false,"excerpt":"Por Gilberto Escobar\u00a0 En Guatemala, durante los \u00faltimos a\u00f1os, los desalojos han ido en aumento y se han dado en dos modalidades: los desalojos legales que tienen una orden judicial y los extrajudiciales, los que\u00a0 no van acompa\u00f1ados de ninguna orden de un juez y que ocurren\u00a0 en horas de\u2026","rel":"","context":"En \u00abBosques\u00bb","block_context":{"text":"Bosques","link":"https:\/\/www.entremundos.org\/revista\/category\/medio-ambiente\/bosques\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/03\/portada.jpg?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/03\/portada.jpg?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/03\/portada.jpg?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/03\/portada.jpg?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":11590,"url":"https:\/\/www.entremundos.org\/revista\/medio-ambiente\/el-habitante-arbol\/","url_meta":{"origin":10750,"position":2},"title":"El habitante \u00e1rbol","author":"EntreMundos","date":"19 enero, 2024","format":false,"excerpt":"POR VALERIA LEIVA La administraci\u00f3n municipal de Quetzaltenango orden\u00f3 la tala de \u00e1rboles en el parque de la zona 3 de la ciudad pero vecinos, comerciantes y expertos se manifestaron en contra de esta decisi\u00f3n.\u00a0 Cada ciudad constituye su propio ecosistema urbano y se suele pensar que en el ecosistema\u2026","rel":"","context":"En \u00abBosques\u00bb","block_context":{"text":"Bosques","link":"https:\/\/www.entremundos.org\/revista\/category\/medio-ambiente\/bosques\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2024\/01\/img_1121-1-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2024\/01\/img_1121-1-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2024\/01\/img_1121-1-scaled.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2024\/01\/img_1121-1-scaled.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2024\/01\/img_1121-1-scaled.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":11083,"url":"https:\/\/www.entremundos.org\/revista\/medio-ambiente\/sin-abejas-no-hay-vida\/","url_meta":{"origin":10750,"position":3},"title":"Sin abejas no hay vida","author":"EntreMundos","date":"20 julio, 2023","format":false,"excerpt":"Ma\u00edz de Vida\u00a0 \u00bfSab\u00edas que a nivel global existen m\u00e1s de 20 mil especies de abejas? Su vida es fundamental para los ecosistemas y la producci\u00f3n de alimentos. Sab\u00edas que una abeja vive menos de 40 d\u00edas, visita al menos 1000 flores y produce menos de una cucharadita de miel,\u2026","rel":"","context":"En \u00abAccion Comunitaria\u00bb","block_context":{"text":"Accion Comunitaria","link":"https:\/\/www.entremundos.org\/revista\/category\/politica\/accion-comunitaria-3\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/07\/a6d4e38f-ec55-4772-bcd2-36fc346e048c-1.jpg?fit=901%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/07\/a6d4e38f-ec55-4772-bcd2-36fc346e048c-1.jpg?fit=901%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/07\/a6d4e38f-ec55-4772-bcd2-36fc346e048c-1.jpg?fit=901%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2023\/07\/a6d4e38f-ec55-4772-bcd2-36fc346e048c-1.jpg?fit=901%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":13642,"url":"https:\/\/www.entremundos.org\/revista\/politica\/las-mujeres-inspiran-es-hora-de-acabar-con-las-brechas-de-desigualdad\/","url_meta":{"origin":10750,"position":4},"title":"Las mujeres inspiran: Es hora de acabar con las brechas de desigualdad","author":"EntreMundos","date":"4 abril, 2026","format":false,"excerpt":"POR MARIANA L\u00d3PEZ La discriminaci\u00f3n y racismo son temas que se han abordado e incluso se ha dicho que ya se han superado estando lejos de ser parte de nuestra realidad, sin embargo, basta con observar para comprender que una cosa es el discurso y otra la pr\u00e1ctica. En la\u2026","rel":"","context":"En \u00abFrontPage\u00bb","block_context":{"text":"FrontPage","link":"https:\/\/www.entremundos.org\/revista\/category\/frontpage\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2026\/03\/649499575_1230883245899060_5224768132019882352_n.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2026\/03\/649499575_1230883245899060_5224768132019882352_n.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2026\/03\/649499575_1230883245899060_5224768132019882352_n.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2026\/03\/649499575_1230883245899060_5224768132019882352_n.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2026\/03\/649499575_1230883245899060_5224768132019882352_n.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2527,"url":"https:\/\/www.entremundos.org\/revista\/economy\/megaprojects\/2527\/?lang=en","url_meta":{"origin":10750,"position":5},"title":"A major march for land and water beings next week","author":"EntreMundos","date":"7 abril, 2016","format":false,"excerpt":"Over 80 organizations that make up the Popular Grassroots Assembly (Asamblea Social y Popular) have planned a march for water, mother earth, land and life that will take place next week and culminate with rallies in Guatemala City on April 22nd \u2013 Earth Day. The goal of the march is\u2026","rel":"","context":"En \u00abCommunity Action\u00bb","block_context":{"text":"Community Action","link":"https:\/\/www.entremundos.org\/revista\/category\/politics\/community-action-en-2\/?lang=en"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.entremundos.org\/revista\/wp-content\/uploads\/2016\/04\/conferencia-de-prensa-para-presnetar-la-marcha-por-el-agua-guatemala.-foto-asp.jpg?fit=400%2C300&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/posts\/10750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/comments?post=10750"}],"version-history":[{"count":3,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/posts\/10750\/revisions"}],"predecessor-version":[{"id":10753,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/posts\/10750\/revisions\/10753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/media\/10712"}],"wp:attachment":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/media?parent=10750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/categories?post=10750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/tags?post=10750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}