{"id":9940,"date":"2022-06-28T10:04:07","date_gmt":"2022-06-28T18:04:07","guid":{"rendered":"https:\/\/www.entremundos.org\/revista\/?p=9940"},"modified":"2022-10-20T08:30:34","modified_gmt":"2022-10-20T16:30:34","slug":"exposicion-itinerante-narra-la-lucha-por-la-justicia-de-las-mujeres-de-sepur-zarco","status":"publish","type":"post","link":"https:\/\/www.entremundos.org\/revista\/salud\/exposicion-itinerante-narra-la-lucha-por-la-justicia-de-las-mujeres-de-sepur-zarco\/","title":{"rendered":"Exposici\u00f3n itinerante narra la lucha por la justicia de las mujeres de Sepur Zarco"},"content":{"rendered":"<p>Una de las galer\u00edas de Casa No\u00b4j, en el Centro Hist\u00f3rico de Quetzaltenango, permite un viaje a trav\u00e9s del tiempo, transporta a las personas a Sepur Zarco, una comunidad en donde durante el Conflicto Armado Interno las mujeres sufrieron violaciones sexuales, servidumbre dom\u00e9stica, tratos humillantes y degradantes.<\/p>\n<p>Tras la firma de los acuerdos de paz, algunas de las mujeres relataron los abusos que sufrieron y comenzaron un camino hacia la justicia, este recorrido tambi\u00e9n se cuenta con 30 im\u00e1genes en la exposici\u00f3n itinerante que estar\u00e1 en Quetzaltenango hasta el 1 de julio de 2022.<\/p>\n<p><a href=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.15-am-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-large wp-image-9943\" src=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.15-am-1-1024x768.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.15-am-1-1024x768.jpeg 1024w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.15-am-1-300x225.jpeg 300w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.15-am-1-768x576.jpeg 768w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.15-am-1-72x54.jpeg 72w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.15-am-1-335x251.jpeg 335w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.15-am-1.jpeg 1040w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p>La denuncia del caso fue presentada en 2011, pero hasta el 26 de febrero de 2016, en el Tribunal de Mayor Riesgo A de Guatemala, fueron condenados Esteelmer Reyes Gir\u00f3n (a 120 a\u00f1os de prisi\u00f3n) y \u00a0Heriberto Valdez (a 240). Ambos responsables de las violencias que sufrieron las mujeres de Sepur Zarco.<\/p>\n<p>En los a\u00f1os 80, el Ej\u00e9rcito de Guatemala instal\u00f3 un destacamento en la comunidad, allan\u00f3 \u00a0casas, desapareci\u00f3 a varios de sus habitantes y oblig\u00f3 a las mujeres a cumplir con turnos en las instalaciones militares. Ellas fueron obligadas a lavar y cocinar para los soldados, adem\u00e1s las agredieron sexualmente.<\/p>\n<p><a href=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-large wp-image-9949\" src=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-2-1024x768.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-2-1024x768.jpeg 1024w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-2-300x225.jpeg 300w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-2-768x576.jpeg 768w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-2-72x54.jpeg 72w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-2-335x251.jpeg 335w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-2.jpeg 1040w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p>A partir de los cr\u00edmenes cometidos por el Ej\u00e9rcito de Guatemala y como parte de la lucha de las mujeres, naci\u00f3 la colectiva Jalok U, integrada por 15 mujeres mayas Q\u00b4echi que como sobrevivientes fueron querellantes en el caso.<\/p>\n<p>Sepur Zarco est\u00e1 ubicada en la regi\u00f3n conocida como el Valle del Polochic, en el municipio de El Estor, Izabal. \u00a0La comunidad a\u00fan espera un centro de salud tipo A y mejoras en los servicios de la educaci\u00f3n p\u00fablica, son parte de las 18 medidas de reparaci\u00f3n digna que las mujeres lograron luego de la sentencia. Pero el Gobierno de Guatemala no ha cumplido con todas.<\/p>\n<p><a href=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-large wp-image-9953\" src=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-1024x768.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-1024x768.jpeg 1024w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-300x225.jpeg 300w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-768x576.jpeg 768w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-72x54.jpeg 72w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-335x251.jpeg 335w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am.jpeg 1040w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p>\u201cEn el caso Sepur Zarco por primera vez el Estado de Guatemala fue condenado en un tribunal guatemalteco por la violaci\u00f3n a los derechos humanos y violaciones sexuales en contra de mujeres Q\u00b4echis por el Ej\u00e9rcito de Guatemala. A\u00fan hay deudas porque el 95 % de las medidas de reparaci\u00f3n no se han cumplido, algunas han iniciado, pero no han concluido\u201d, dijo Brenda Maldonado, coordinadora de la sede de la organizaci\u00f3n Mujeres Transformando el Mundo (MTM).<\/p>\n<p>En el 2009, MTM se unieron al esfuerzo para obtener justicia, apoyaron al grupo de sobrevivientes con un litigio estrat\u00e9gico del caso y en la actualidad colaboran con la memoria hist\u00f3rica por medio de la exposici\u00f3n itinerante que relata el caso de las mujeres de Sepur Zarco. La muestra est\u00e1 abierta en Casa No\u00b4j, zona 1 de Quetzaltenango, de 9 a 16 horas.<\/p>\n<p><a href=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-3.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-large wp-image-9951\" src=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-3-1024x768.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-3-1024x768.jpeg 1024w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-3-300x225.jpeg 300w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-3-768x576.jpeg 768w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-3-72x54.jpeg 72w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-3-335x251.jpeg 335w, https:\/\/www.entremundos.org\/revista\/wp-content\/uploads\/2022\/06\/whatsapp-image-2022-06-28-at-11.35.16-am-3.jpeg 1040w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las galer\u00edas de Casa No\u00b4j, en el Centro Hist\u00f3rico de Quetzaltenango, permite un viaje a trav\u00e9s del tiempo, transporta a las personas a Sepur Zarco, una comunidad en donde durante el Conflicto Armado Interno las mujeres sufrieron violaciones sexuales, servidumbre dom\u00e9stica, tratos humillantes y degradantes. Tras la firma de los acuerdos de paz, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[402,388,439,386,382],"tags":[3827,1179,3828,65,3826,3825,3829,3830,107,846,3831],"class_list":["post-9940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accion-comunitaria-3","category-cultura","category-juventud","category-mujer","category-salud","tag-condena-sepur-zarco","tag-conflicto-armado-interno","tag-exposicion-itenerante-del-caso-sepur-zarco","tag-guatemala","tag-mujeres-qechi","tag-mujeres-sepur-zarco","tag-mujeres-transformando-el-mundo","tag-mujeres-violaciones","tag-quetzaltenango","tag-sepur-zarco","tag-servidumbre-sexual-y-domestica"],"_links":{"self":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/posts\/9940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/comments?post=9940"}],"version-history":[{"count":1,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/posts\/9940\/revisions"}],"predecessor-version":[{"id":9955,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/posts\/9940\/revisions\/9955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/media\/9941"}],"wp:attachment":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/media?parent=9940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/categories?post=9940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/tags?post=9940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}