{"id":4044,"count":1,"description":"","link":"https:\/\/www.entremundos.org\/revista\/tag\/canasta-basica-alimentaria-en-guatemala\/","name":"Canasta b\u00e1sica alimentaria en Guatemala","slug":"canasta-basica-alimentaria-en-guatemala","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/tags\/4044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/posts?tags=4044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}