{"id":666,"count":1,"description":"","link":"https:\/\/www.entremundos.org\/revista\/tag\/tortilla\/","name":"tortilla","slug":"tortilla","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/tags\/666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.entremundos.org\/revista\/wp-json\/wp\/v2\/posts?tags=666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}